{"id":128,"date":"2023-02-22T21:52:00","date_gmt":"2023-02-22T21:52:00","guid":{"rendered":"http:\/\/notitech.cl\/?p=128"},"modified":"2023-03-26T00:53:29","modified_gmt":"2023-03-26T00:53:29","slug":"gpt-4-que-es-novedades-y-cuando-saldra-la-nueva-ia-que-mejorara-chatgpt","status":"publish","type":"post","link":"https:\/\/notitech.cl\/index.php\/2023\/02\/22\/gpt-4-que-es-novedades-y-cuando-saldra-la-nueva-ia-que-mejorara-chatgpt\/","title":{"rendered":"GPT 4: qu\u00e9 es, novedades y cu\u00e1ndo saldr\u00e1 la nueva IA que mejorar\u00e1 ChatGPT"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/notitech.cl\/wp-content\/uploads\/2023\/03\/gpt4.jpg\" alt=\"\" class=\"wp-image-129\" width=\"820\" height=\"544\" srcset=\"https:\/\/notitech.cl\/wp-content\/uploads\/2023\/03\/gpt4.jpg 956w, https:\/\/notitech.cl\/wp-content\/uploads\/2023\/03\/gpt4-300x199.jpg 300w, https:\/\/notitech.cl\/wp-content\/uploads\/2023\/03\/gpt4-768x509.jpg 768w\" sizes=\"auto, (max-width: 820px) 100vw, 820px\" \/><\/figure>\n\n\n\n<p><a href=\"https:\/\/hipertextual.com\/2022\/12\/chatgpt-que-es-como-usar\">ChatGPT<\/a>&nbsp;y otras herramientas que utilizan uno de los modelos de lenguaje m\u00e1s avanzados de OpenAI, podr\u00eda dar un paso m\u00e1s all\u00e1 durante los pr\u00f3ximos meses. La compa\u00f1\u00eda especializada en el desarrollo de modelos de IA se prepara para lanzar&nbsp;<strong>GPT 4 y ChatGPT 4<\/strong>, que prometen ofrecer importantes avances frente a GPT-3 y, por tanto, mejorar no solo el popular chatbot que tanto cautiva a los usuarios, pero cuyas respuestas no siempre son exactas, sino otros servicios basados en esta inteligencia artificial. Entre ellos,&nbsp;<a href=\"https:\/\/hipertextual.com\/2023\/02\/microsoft-bing-chatgpt-exito\">el nuevo Bing<\/a>.<\/p>\n\n\n\n<p>GPT 4 en concreto,&nbsp;<strong>llegar\u00e1 para renovar a GPT-3.5<\/strong>, una versi\u00f3n actualizada de la tercera generaci\u00f3n del modelo de procesamiento de lenguaje que la compa\u00f1\u00eda lanz\u00f3 en 2020 y que, precisamente, es la que&nbsp;<a href=\"https:\/\/hipertextual.com\/2023\/03\/bing-chatgpt-utiliza-gpt-4-openai\">Microsoft usa en el nuevo Bing<\/a>.<\/p>\n\n\n\n<p>La nueva IA promete mejorar su capacidad de respuesta y realizar tareas de una forma m\u00e1s precisa, r\u00e1pida y eficiente, gracias a cambios relevantes que OpenAI ya ha adelantado.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">GPT 4: \u00bfqu\u00e9 mejoras llegar\u00e1n a la nueva IA?<\/h2>\n\n\n\n<p>Uno de estos cambios de&nbsp;<a href=\"https:\/\/hipertextual.com\/2023\/03\/openai-anuncia-gpt-4-el-nuevo-modelo-que-revolucionara-chatgpt-y-dall-e\">GPT-4<\/a>&nbsp;frente a GPT-3.5, y probablemente el m\u00e1s importante, es su tama\u00f1o de procesamiento. La nueva versi\u00f3n&nbsp;<strong>llegar\u00e1 con una capacidad de par\u00e1metros de aprendizaje autom\u00e1tico hasta 500 veces mayor&nbsp;<\/strong>que la versi\u00f3n actual que incluye ChatGPT o el chatbot de Bing.<\/p>\n\n\n\n<p>Esto se traduce la posibilidad de dar respuestas m\u00e1s exactas y de una manera m\u00e1s r\u00e1pida, por lo que es probable que la nueva versi\u00f3n solvente uno de los principales inconvenientes de GPT-3: la posibilidad de ofrecer respuestas inexactas en algunos casos.<\/p>\n\n\n\n<p>Esta mejora en el tama\u00f1o de procesamiento tambi\u00e9n<strong>\u00a0se traduce en textos de mayor calidad y con respuestas m\u00e1s coherentes,<\/strong>\u00a0incluso, sin necesidad de ofrecerle tanto contexto. La nueva IA, adem\u00e1s, tambi\u00e9n ser\u00e1 capaz de realizar traducciones autom\u00e1ticas.<\/p>\n\n\n\n<p><strong>GPT 4 dar\u00e1 respuestas m\u00e1s actuales<\/strong><\/p>\n\n\n\n<p>GPT 4, por otro lado, promete mejorar otro de los inconvenientes de GPT-3:<strong>&nbsp;sus respuestas nada actualizadas<\/strong>. Por ejemplo, si a d\u00eda de hoy le preguntas a ChatGPT (basado en GPT-3.5), cu\u00e1l es el \u00faltimo iPhone, te dar\u00e1 la siguiente respuesta: \u201cEl \u00faltimo modelo de iPhone lanzado por Apple hasta la fecha es el iPhone 13, que fue presentado en septiembre de 2021 [\u2026]\u201d.<\/p>\n\n\n\n<p>El \u00faltimo iPhone, sin embargo, es el iPhone 14. Pero como la IA no se ha actualizado desde 2021, no es capaz de saber que hay una nueva versi\u00f3n del m\u00f3vil de Apple. Por tanto, con GPT 4,\u00a0<strong>podremos obtener\u00a0<a href=\"https:\/\/hipertextual.com\/2023\/03\/gpt-4-supera-chatgpt-examenes-universitarios\">respuestas m\u00e1s actuales<\/a>\u00a0y, por ende, m\u00e1s exactas.<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">GPT-4 vs GPT-3: principales diferencias<\/h2>\n\n\n\n<p>GPT-4 tendr\u00e1 importantes diferencias frente a GPT-3, pese a que funcionar\u00e1n de manera similar; pues ambos son modelos de lenguaje dedicados a generar texto. Uno de los cambios m\u00e1s relevantes, y que ya hemos comentado previamente, es que&nbsp;<strong>GPT-4 ser\u00e1 capaz de ofrecer respuestas mucho m\u00e1s precisas<\/strong>&nbsp;y coherentes, incluso con falta de contexto o con preguntas mal formuladas.<\/p>\n\n\n\n<p>GPT-4, adem\u00e1s,&nbsp;<strong>podr\u00eda ser m\u00e1s \u00e9tica frente a GPT-3 o GPT-3.5<\/strong>&nbsp;con el objetivo de evitar que los usuarios utilicen la IA para generar contenido enga\u00f1oso o manipulativo.<\/p>\n\n\n\n<p>Otra diferencia de GPT-4 vs GPT-3 es la\u00a0<strong>posibilidad de generar traducciones autom\u00e1ticas,\u00a0<\/strong>algo que el actual modelo de OpenAI no puede hacer. Tambi\u00e9n, reiteramos, GPT-4 dar\u00e1\u00a0<strong>respuestas m\u00e1s actuales<\/strong>, por lo que ser\u00e1 posible realizar preguntas relacionadas con acontecimientos que han sucedido recientemente.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u00bfLlegar\u00e1n estas novedades a ChatGPT 4?<\/h2>\n\n\n\n<p>Por supuesto, los avances que veremos en GPT 4, tambi\u00e9n estar\u00e1n presentes en una futura versi\u00f3n del chatbot de OpenAI.&nbsp;<strong>ChatGPT 4<\/strong>, en concreto, podr\u00eda ser m\u00e1s r\u00e1pido ofreciendo respuestas. Su tasa de fallos o de resultados inexactos, adem\u00e1s, ser\u00eda considerablemente menor.<\/p>\n\n\n\n<p>Ahora bien, no debemos olvidar que\u00a0<a href=\"https:\/\/hipertextual.com\/2023\/02\/chatgpt-plus-version-pago-ia\">el chatbot tiene una versi\u00f3n de pago<\/a>\u00a0en la que, por 20 d\u00f3lares al mes, los usuarios pueden disfrutar de algunas ventajas frente al plan gratuito. Entre ellas, acceso inmediato en horas punta o acceso prioritario a nuevas funciones y mejoras del modelo. Por tanto,\u00a0<strong>es muy probable que aquellos usuarios del plan \u201cPlus\u201d sean los primeros en probar ChatGPT 4.<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u00bfSe actualizar\u00e1 Bing con la nueva IA?<\/h2>\n\n\n\n<p>Donde tambi\u00e9n podr\u00edamos ver<strong>&nbsp;importantes mejoras es en Bing<\/strong>, buscador que, recordemos, ahora est\u00e1 impulsado gracias a GPT-3.5 y cuyo chatbot es algo m\u00e1s avanzado que ChatGPT, gracias a la posibilidad de nutrirse de los resultados de b\u00fasqueda. Es decir, el chat de Bing s\u00ed puede ofrecer respuestas actualizadas con GPT-3.5, pues busca en la web, por ejemplo, cu\u00e1l es el \u00faltimo iPhone y compara diferentes resultados para sacar conclusiones.<\/p>\n\n\n\n<p>Ahora bien, el chatbot de Bing tampoco es perfecto, y adem\u00e1s de dar respuestas inexactas o, incluso, inventadas en muchos casos, tambi\u00e9n tiende a perder la cabeza si recibe demasiadas preguntas en una misma conversaci\u00f3n. GPT 4 y su mejorada capacidad de par\u00e1metros de aprendizaje autom\u00e1tico podr\u00eda solucionar este problema.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u00bfPara qu\u00e9 podremos usar GPT 4?<\/h2>\n\n\n\n<p>GPT 4 tendr\u00e1 diferentes aplicaciones para el d\u00eda a d\u00eda. Entre ellas, la posibilidad de traducir textos o de, incluso, crear aplicaciones mediante la generaci\u00f3n de c\u00f3digo. Estos son algunos&nbsp;<a href=\"https:\/\/hipertextual.com\/2023\/03\/que-significan-siglas-gpt-gpt-4-chatgpt\">ejemplos<\/a>&nbsp;de uso de GPT 4<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-traduccion-de-idiomas\">Traducci\u00f3n de idiomas<\/h3>\n\n\n\n<p>Ser\u00e1 posible, por ejemplo, insertar un texto y pedirle a GPT 4 que lo traduzca al espa\u00f1ol o a cualquier otro idioma.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-busquedas-de-consultas\">B\u00fasquedas de consultas<\/h3>\n\n\n\n<p>Tal y como hacemos en Google. Por ejemplo, preguntarle sobre una receta, cu\u00e1l es el \u00faltimo m\u00f3vil de Samsung, etc.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-solicitud-de-textos\">Solicitud de textos<\/h3>\n\n\n\n<p>Ser\u00e1 posible pedirle que redacte un texto pidiendo una cita, que escriba un mensaje sobre lo bien que ha ido una reuni\u00f3n, etc.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-generar-codigo\">Generar c\u00f3digo<\/h3>\n\n\n\n<p>GPT 4 tambi\u00e9n ser\u00e1 capaz de generar l\u00edneas de c\u00f3digo para la creaci\u00f3n de aplicaciones b\u00e1sicas.<\/p>\n\n\n\n<p>GPT 4, adem\u00e1s,<strong>\u00a0podr\u00e1 integrarse en algunas plataformas, aplicaciones y programas<\/strong>\u00a0de terceros. Por ejemplo, GPT 4 en Outlook o en una aplicaci\u00f3n de mail similar, puede resultar \u00fatil para ofrecer respuestas relacionadas con el correo electr\u00f3nico que hemos recibido.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">GPT 4 y ChatGPT 4: \u00bfcu\u00e1ndo se lanzar\u00e1 y cu\u00e1ndo podremos probar la nueva IA?<\/h2>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"570\" src=\"http:\/\/notitech.cl\/wp-content\/uploads\/2023\/03\/gpt4_-1024x570.jpg\" alt=\"\" class=\"wp-image-130\" srcset=\"https:\/\/notitech.cl\/wp-content\/uploads\/2023\/03\/gpt4_-1024x570.jpg 1024w, https:\/\/notitech.cl\/wp-content\/uploads\/2023\/03\/gpt4_-300x167.jpg 300w, https:\/\/notitech.cl\/wp-content\/uploads\/2023\/03\/gpt4_-768x427.jpg 768w, https:\/\/notitech.cl\/wp-content\/uploads\/2023\/03\/gpt4_.jpg 1091w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Por el momento, OpenAI no ha anunciado cu\u00e1ndo estar\u00e1 disponible GPT 4 y, por ende, ChatGPT 4.&nbsp;<a href=\"https:\/\/techcrunch.com\/2022\/12\/01\/while-anticipation-builds-for-gpt-4-openai-quietly-releases-gpt-3-5\/\" target=\"_blank\" rel=\"noreferrer noopener\">Se espera<\/a>, sin embargo, que la compa\u00f1\u00eda lance la nueva versi\u00f3n de la IA&nbsp;<strong>a lo largo de este 2023.<\/strong>&nbsp;Si tenemos en cuenta que GPT-3.5 se lanz\u00f3 en noviembre de 2022, es probable que GPT 4 llegue, como m\u00ednimo, seis meses despu\u00e9s. Es decir, durante el mes de mayo.<\/p>\n\n\n\n<p><strong>La mejor manera de probar GPT 4 ser\u00e1 a trav\u00e9s de ChatGPT 4<\/strong>\u00a0que, reiteramos, estar\u00eda disponible en primer lugar para aquellos usuarios que paguen el plan mensual de ChatGPT Plus. En cualquier caso, la nueva versi\u00f3n del chatbot podr\u00eda llegar m\u00e1s adelante del lanzamiento de GPT 4, pues el modelo de lenguaje tambi\u00e9n tiene otras aplicaciones m\u00e1s all\u00e1 de poder realizar conversaciones con una IA.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">GPT 4 llegar\u00e1 la pr\u00f3xima semana<\/h2>\n\n\n\n<p>Andreas Braun, director de tecnolog\u00eda de Microsoft Alemania, ha confirmado este 9 de marzo que GPT-4 se anunciar\u00e1 la pr\u00f3xima semana. Es decir, a partir del pr\u00f3ximo 13 de marzo. Braun ha detallado, adem\u00e1s, que la nueva IA de OpenAI\u00a0<strong>ser\u00e1 un modelo de lenguaje multimodal<\/strong>. Esto quiere decir que GPT-4 no solo ser\u00e1 capaz de generar texto, como ya hace GPT-3, sino que tambi\u00e9n podr\u00e1 crear im\u00e1genes, m\u00fasica e, incluso, v\u00eddeos.<\/p>\n\n\n\n<p>El director de tecnolog\u00eda de Microsoft en Alemania tambi\u00e9n ha querido minimizar las preocupaciones entorno a c\u00f3mo\u00a0<strong>la IA podr\u00eda ser capaz de reemplazar algunos puestos de trabajo.<\/strong>\u00a0Asegura que el objetivo de GPT-4 no es sustituir al humano, sino ayudarle en aquellas tareas repetitivas. \u201cNo se trata de reemplazar puestos de trabajo, sino de hacer tareas repetitivas de una manera diferente a como se hac\u00eda antes\u201d, subraya.<\/p>\n\n\n\n<p>FUENTE: <a href=\"https:\/\/hipertextual.com\/2023\/02\/gpt-4-que-es-cuando-sadra-novedades\" target=\"_blank\" rel=\"noreferrer noopener\">Hipertextual<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>ChatGPT&nbsp;y otras herramientas que utilizan uno de los modelos de lenguaje m\u00e1s avanzados de OpenAI, podr\u00eda dar un<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[113,114,115,55,56,58],"class_list":["post-128","post","type-post","status-publish","format-standard","hentry","category-inteligencia-artificial","tag-bing","tag-gpt3","tag-gpt4","tag-ia","tag-inteligencia-artificial","tag-openia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>GPT 4: qu\u00e9 es, novedades y cu\u00e1ndo saldr\u00e1 la nueva IA que mejorar\u00e1 ChatGPT - Notitech<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/notitech.cl\/index.php\/2023\/02\/22\/gpt-4-que-es-novedades-y-cuando-saldra-la-nueva-ia-que-mejorara-chatgpt\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"GPT 4: qu\u00e9 es, novedades y cu\u00e1ndo saldr\u00e1 la nueva IA que mejorar\u00e1 ChatGPT - Notitech\" \/>\n<meta property=\"og:description\" content=\"ChatGPT&nbsp;y otras herramientas que utilizan uno de los modelos de lenguaje m\u00e1s avanzados de OpenAI, podr\u00eda dar un\" \/>\n<meta property=\"og:url\" content=\"http:\/\/notitech.cl\/index.php\/2023\/02\/22\/gpt-4-que-es-novedades-y-cuando-saldra-la-nueva-ia-que-mejorara-chatgpt\/\" \/>\n<meta property=\"og:site_name\" content=\"Notitech\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-22T21:52:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-26T00:53:29+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/notitech.cl\/wp-content\/uploads\/2023\/03\/gpt4.jpg\" \/>\n<meta name=\"author\" content=\"tano\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@notitech_cl\" \/>\n<meta name=\"twitter:site\" content=\"@notitech_cl\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"tano\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\/\/notitech.cl\/index.php\/2023\/02\/22\/gpt-4-que-es-novedades-y-cuando-saldra-la-nueva-ia-que-mejorara-chatgpt\/#article\",\"isPartOf\":{\"@id\":\"http:\/\/notitech.cl\/index.php\/2023\/02\/22\/gpt-4-que-es-novedades-y-cuando-saldra-la-nueva-ia-que-mejorara-chatgpt\/\"},\"author\":{\"name\":\"tano\",\"@id\":\"http:\/\/notitech.cl\/#\/schema\/person\/d1cd50bb099396f5d7873b5b15a646bc\"},\"headline\":\"GPT 4: qu\u00e9 es, novedades y cu\u00e1ndo saldr\u00e1 la nueva IA que mejorar\u00e1 ChatGPT\",\"datePublished\":\"2023-02-22T21:52:00+00:00\",\"dateModified\":\"2023-03-26T00:53:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\/\/notitech.cl\/index.php\/2023\/02\/22\/gpt-4-que-es-novedades-y-cuando-saldra-la-nueva-ia-que-mejorara-chatgpt\/\"},\"wordCount\":1367,\"publisher\":{\"@id\":\"http:\/\/notitech.cl\/#organization\"},\"image\":{\"@id\":\"http:\/\/notitech.cl\/index.php\/2023\/02\/22\/gpt-4-que-es-novedades-y-cuando-saldra-la-nueva-ia-que-mejorara-chatgpt\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/notitech.cl\/wp-content\/uploads\/2023\/03\/gpt4.jpg\",\"keywords\":[\"Bing\",\"GPT3\",\"GPT4\",\"IA\",\"Inteligencia Artificial\",\"OpenIA\"],\"articleSection\":[\"Inteligencia Artificial\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/notitech.cl\/index.php\/2023\/02\/22\/gpt-4-que-es-novedades-y-cuando-saldra-la-nueva-ia-que-mejorara-chatgpt\/\",\"url\":\"http:\/\/notitech.cl\/index.php\/2023\/02\/22\/gpt-4-que-es-novedades-y-cuando-saldra-la-nueva-ia-que-mejorara-chatgpt\/\",\"name\":\"GPT 4: qu\u00e9 es, novedades y cu\u00e1ndo saldr\u00e1 la nueva IA que mejorar\u00e1 ChatGPT - Notitech\",\"isPartOf\":{\"@id\":\"http:\/\/notitech.cl\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/notitech.cl\/index.php\/2023\/02\/22\/gpt-4-que-es-novedades-y-cuando-saldra-la-nueva-ia-que-mejorara-chatgpt\/#primaryimage\"},\"image\":{\"@id\":\"http:\/\/notitech.cl\/index.php\/2023\/02\/22\/gpt-4-que-es-novedades-y-cuando-saldra-la-nueva-ia-que-mejorara-chatgpt\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/notitech.cl\/wp-content\/uploads\/2023\/03\/gpt4.jpg\",\"datePublished\":\"2023-02-22T21:52:00+00:00\",\"dateModified\":\"2023-03-26T00:53:29+00:00\",\"breadcrumb\":{\"@id\":\"http:\/\/notitech.cl\/index.php\/2023\/02\/22\/gpt-4-que-es-novedades-y-cuando-saldra-la-nueva-ia-que-mejorara-chatgpt\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/notitech.cl\/index.php\/2023\/02\/22\/gpt-4-que-es-novedades-y-cuando-saldra-la-nueva-ia-que-mejorara-chatgpt\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"http:\/\/notitech.cl\/index.php\/2023\/02\/22\/gpt-4-que-es-novedades-y-cuando-saldra-la-nueva-ia-que-mejorara-chatgpt\/#primaryimage\",\"url\":\"https:\/\/notitech.cl\/wp-content\/uploads\/2023\/03\/gpt4.jpg\",\"contentUrl\":\"https:\/\/notitech.cl\/wp-content\/uploads\/2023\/03\/gpt4.jpg\",\"width\":956,\"height\":634},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/notitech.cl\/index.php\/2023\/02\/22\/gpt-4-que-es-novedades-y-cuando-saldra-la-nueva-ia-que-mejorara-chatgpt\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"http:\/\/notitech.cl\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"GPT 4: qu\u00e9 es, novedades y cu\u00e1ndo saldr\u00e1 la nueva IA que mejorar\u00e1 ChatGPT\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\/\/notitech.cl\/#website\",\"url\":\"http:\/\/notitech.cl\/\",\"name\":\"Notitech\",\"description\":\"Todo sobre tecnolog\u00eda\",\"publisher\":{\"@id\":\"http:\/\/notitech.cl\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/notitech.cl\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"http:\/\/notitech.cl\/#organization\",\"name\":\"Notitech\",\"url\":\"http:\/\/notitech.cl\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"http:\/\/notitech.cl\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/notitech.cl\/wp-content\/uploads\/2023\/02\/logo.jpg\",\"contentUrl\":\"http:\/\/notitech.cl\/wp-content\/uploads\/2023\/02\/logo.jpg\",\"width\":462,\"height\":417,\"caption\":\"Notitech\"},\"image\":{\"@id\":\"http:\/\/notitech.cl\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/notitech_cl\"]},{\"@type\":\"Person\",\"@id\":\"http:\/\/notitech.cl\/#\/schema\/person\/d1cd50bb099396f5d7873b5b15a646bc\",\"name\":\"tano\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"http:\/\/notitech.cl\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/20d89588ca8b2d7415b38b7f5c88580bd7a3d3f58595f80e8a140a6915c65be5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/20d89588ca8b2d7415b38b7f5c88580bd7a3d3f58595f80e8a140a6915c65be5?s=96&d=mm&r=g\",\"caption\":\"tano\"},\"sameAs\":[\"https:\/\/notitech.cl\"],\"url\":\"https:\/\/notitech.cl\/index.php\/author\/tano\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"GPT 4: qu\u00e9 es, novedades y cu\u00e1ndo saldr\u00e1 la nueva IA que mejorar\u00e1 ChatGPT - Notitech","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/notitech.cl\/index.php\/2023\/02\/22\/gpt-4-que-es-novedades-y-cuando-saldra-la-nueva-ia-que-mejorara-chatgpt\/","og_locale":"es_ES","og_type":"article","og_title":"GPT 4: qu\u00e9 es, novedades y cu\u00e1ndo saldr\u00e1 la nueva IA que mejorar\u00e1 ChatGPT - Notitech","og_description":"ChatGPT&nbsp;y otras herramientas que utilizan uno de los modelos de lenguaje m\u00e1s avanzados de OpenAI, podr\u00eda dar un","og_url":"http:\/\/notitech.cl\/index.php\/2023\/02\/22\/gpt-4-que-es-novedades-y-cuando-saldra-la-nueva-ia-que-mejorara-chatgpt\/","og_site_name":"Notitech","article_published_time":"2023-02-22T21:52:00+00:00","article_modified_time":"2023-03-26T00:53:29+00:00","og_image":[{"url":"http:\/\/notitech.cl\/wp-content\/uploads\/2023\/03\/gpt4.jpg","type":"","width":"","height":""}],"author":"tano","twitter_card":"summary_large_image","twitter_creator":"@notitech_cl","twitter_site":"@notitech_cl","twitter_misc":{"Escrito por":"tano","Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/notitech.cl\/index.php\/2023\/02\/22\/gpt-4-que-es-novedades-y-cuando-saldra-la-nueva-ia-que-mejorara-chatgpt\/#article","isPartOf":{"@id":"http:\/\/notitech.cl\/index.php\/2023\/02\/22\/gpt-4-que-es-novedades-y-cuando-saldra-la-nueva-ia-que-mejorara-chatgpt\/"},"author":{"name":"tano","@id":"http:\/\/notitech.cl\/#\/schema\/person\/d1cd50bb099396f5d7873b5b15a646bc"},"headline":"GPT 4: qu\u00e9 es, novedades y cu\u00e1ndo saldr\u00e1 la nueva IA que mejorar\u00e1 ChatGPT","datePublished":"2023-02-22T21:52:00+00:00","dateModified":"2023-03-26T00:53:29+00:00","mainEntityOfPage":{"@id":"http:\/\/notitech.cl\/index.php\/2023\/02\/22\/gpt-4-que-es-novedades-y-cuando-saldra-la-nueva-ia-que-mejorara-chatgpt\/"},"wordCount":1367,"publisher":{"@id":"http:\/\/notitech.cl\/#organization"},"image":{"@id":"http:\/\/notitech.cl\/index.php\/2023\/02\/22\/gpt-4-que-es-novedades-y-cuando-saldra-la-nueva-ia-que-mejorara-chatgpt\/#primaryimage"},"thumbnailUrl":"http:\/\/notitech.cl\/wp-content\/uploads\/2023\/03\/gpt4.jpg","keywords":["Bing","GPT3","GPT4","IA","Inteligencia Artificial","OpenIA"],"articleSection":["Inteligencia Artificial"],"inLanguage":"es"},{"@type":"WebPage","@id":"http:\/\/notitech.cl\/index.php\/2023\/02\/22\/gpt-4-que-es-novedades-y-cuando-saldra-la-nueva-ia-que-mejorara-chatgpt\/","url":"http:\/\/notitech.cl\/index.php\/2023\/02\/22\/gpt-4-que-es-novedades-y-cuando-saldra-la-nueva-ia-que-mejorara-chatgpt\/","name":"GPT 4: qu\u00e9 es, novedades y cu\u00e1ndo saldr\u00e1 la nueva IA que mejorar\u00e1 ChatGPT - Notitech","isPartOf":{"@id":"http:\/\/notitech.cl\/#website"},"primaryImageOfPage":{"@id":"http:\/\/notitech.cl\/index.php\/2023\/02\/22\/gpt-4-que-es-novedades-y-cuando-saldra-la-nueva-ia-que-mejorara-chatgpt\/#primaryimage"},"image":{"@id":"http:\/\/notitech.cl\/index.php\/2023\/02\/22\/gpt-4-que-es-novedades-y-cuando-saldra-la-nueva-ia-que-mejorara-chatgpt\/#primaryimage"},"thumbnailUrl":"http:\/\/notitech.cl\/wp-content\/uploads\/2023\/03\/gpt4.jpg","datePublished":"2023-02-22T21:52:00+00:00","dateModified":"2023-03-26T00:53:29+00:00","breadcrumb":{"@id":"http:\/\/notitech.cl\/index.php\/2023\/02\/22\/gpt-4-que-es-novedades-y-cuando-saldra-la-nueva-ia-que-mejorara-chatgpt\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["http:\/\/notitech.cl\/index.php\/2023\/02\/22\/gpt-4-que-es-novedades-y-cuando-saldra-la-nueva-ia-que-mejorara-chatgpt\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"http:\/\/notitech.cl\/index.php\/2023\/02\/22\/gpt-4-que-es-novedades-y-cuando-saldra-la-nueva-ia-que-mejorara-chatgpt\/#primaryimage","url":"https:\/\/notitech.cl\/wp-content\/uploads\/2023\/03\/gpt4.jpg","contentUrl":"https:\/\/notitech.cl\/wp-content\/uploads\/2023\/03\/gpt4.jpg","width":956,"height":634},{"@type":"BreadcrumbList","@id":"http:\/\/notitech.cl\/index.php\/2023\/02\/22\/gpt-4-que-es-novedades-y-cuando-saldra-la-nueva-ia-que-mejorara-chatgpt\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"http:\/\/notitech.cl\/"},{"@type":"ListItem","position":2,"name":"GPT 4: qu\u00e9 es, novedades y cu\u00e1ndo saldr\u00e1 la nueva IA que mejorar\u00e1 ChatGPT"}]},{"@type":"WebSite","@id":"http:\/\/notitech.cl\/#website","url":"http:\/\/notitech.cl\/","name":"Notitech","description":"Todo sobre tecnolog\u00eda","publisher":{"@id":"http:\/\/notitech.cl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/notitech.cl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"http:\/\/notitech.cl\/#organization","name":"Notitech","url":"http:\/\/notitech.cl\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"http:\/\/notitech.cl\/#\/schema\/logo\/image\/","url":"http:\/\/notitech.cl\/wp-content\/uploads\/2023\/02\/logo.jpg","contentUrl":"http:\/\/notitech.cl\/wp-content\/uploads\/2023\/02\/logo.jpg","width":462,"height":417,"caption":"Notitech"},"image":{"@id":"http:\/\/notitech.cl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/notitech_cl"]},{"@type":"Person","@id":"http:\/\/notitech.cl\/#\/schema\/person\/d1cd50bb099396f5d7873b5b15a646bc","name":"tano","image":{"@type":"ImageObject","inLanguage":"es","@id":"http:\/\/notitech.cl\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/20d89588ca8b2d7415b38b7f5c88580bd7a3d3f58595f80e8a140a6915c65be5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/20d89588ca8b2d7415b38b7f5c88580bd7a3d3f58595f80e8a140a6915c65be5?s=96&d=mm&r=g","caption":"tano"},"sameAs":["https:\/\/notitech.cl"],"url":"https:\/\/notitech.cl\/index.php\/author\/tano\/"}]}},"_links":{"self":[{"href":"https:\/\/notitech.cl\/index.php\/wp-json\/wp\/v2\/posts\/128","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/notitech.cl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/notitech.cl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/notitech.cl\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/notitech.cl\/index.php\/wp-json\/wp\/v2\/comments?post=128"}],"version-history":[{"count":1,"href":"https:\/\/notitech.cl\/index.php\/wp-json\/wp\/v2\/posts\/128\/revisions"}],"predecessor-version":[{"id":131,"href":"https:\/\/notitech.cl\/index.php\/wp-json\/wp\/v2\/posts\/128\/revisions\/131"}],"wp:attachment":[{"href":"https:\/\/notitech.cl\/index.php\/wp-json\/wp\/v2\/media?parent=128"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/notitech.cl\/index.php\/wp-json\/wp\/v2\/categories?post=128"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/notitech.cl\/index.php\/wp-json\/wp\/v2\/tags?post=128"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}